{"id":117538,"date":"2023-12-15T11:14:38","date_gmt":"2023-12-15T11:14:38","guid":{"rendered":"https:\/\/savio.it\/unternehmen\/"},"modified":"2023-12-15T13:33:29","modified_gmt":"2023-12-15T13:33:29","slug":"azienda","status":"publish","type":"page","link":"https:\/\/savio.it\/de\/azienda\/","title":{"rendered":"Unternehmen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"117538\" class=\"elementor elementor-117538 elementor-3612\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ef0476 elementor-section-full_width elementor-section-stretched img-copertina-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"0ef0476\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87bcd3f\" data-id=\"87bcd3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c0d5c9 elementor-widget elementor-widget-heading\" data-id=\"5c0d5c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">UNTERNEHMEN<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c72ca6 elementor-widget elementor-widget-heading\" data-id=\"8c72ca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Savio Group<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1de2692 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1de2692\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19760c0\" data-id=\"19760c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-522025a elementor-widget elementor-widget-heading\" data-id=\"522025a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4t ist unser <br \/>Ziel... seit 130 Jahren<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47d997c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47d997c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ebfdea6\" data-id=\"ebfdea6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2370acd elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"2370acd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie Qualit\u00e4t und Innovation der Produkte der Savio Group (mehr als 5.600 im Katalog) beruht auf \u00fcber 190 weltweit angemeldeten Patenten.\r\n<br\/><br\/>\r\nSavio Group ist auf der ganzen Welt vertreten, mit einem weit verzweigten Netz von Vertriebspartnern und Niederlassungen, die einen globalen Vertrieb von Produkten \u201eMade in Italy\u201c gew\u00e4hrleisten..\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08df1c7\" data-id=\"08df1c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f6ea0c elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7f6ea0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo.jpg\" class=\"attachment-large size-large wp-image-66649\" alt=\"qualit\u00e0-il-nostro-obiettivo\" srcset=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo.jpg 1024w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo-600x338.jpg 600w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo-300x169.jpg 300w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f56d09 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"5f56d09\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddfcdfd\" data-id=\"ddfcdfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09d0aa3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"09d0aa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cda08ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cda08ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50c7f39\" data-id=\"50c7f39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83434d5 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"83434d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Qualita.jpg\" class=\"attachment-large size-large wp-image-66655\" alt=\"Qualit\u00e0\" srcset=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Qualita.jpg 1024w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Qualita-600x338.jpg 600w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Qualita-300x169.jpg 300w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Qualita-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d0e8b4c\" data-id=\"d0e8b4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7bd15b elementor-widget elementor-widget-heading\" data-id=\"c7bd15b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Abnahmen und Pr\u00fcfungen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7d651a elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"d7d651a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jedes Produkt wird nach strengsten<br \/>europ\u00e4ischen Normen gepr\u00fcft und zertifiziert.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a64d96 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"4a64d96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10accbc\" data-id=\"10accbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6525d1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d6525d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d0c74f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d0c74f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b01a41\" data-id=\"8b01a41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a267870 elementor-widget elementor-widget-heading\" data-id=\"a267870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Innovation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a731536 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"a731536\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mehr als 190 patentierte Produkte,<br \/>das Ergebnis einer j\u00e4hrlichen Investition von 5% des Umsatzes<br \/>in Forschung und Entwicklung.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-769fdab\" data-id=\"769fdab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0df2e6 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e0df2e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Innovazione.jpg\" class=\"attachment-large size-large wp-image-66661\" alt=\"Innovazione\" srcset=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Innovazione.jpg 1024w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Innovazione-600x338.jpg 600w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Innovazione-300x169.jpg 300w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Innovazione-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9beb31f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9beb31f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9afdfb5\" data-id=\"9afdfb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffbe20d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ffbe20d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3df86a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3df86a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8090303\" data-id=\"8090303\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bf0e32 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2bf0e32\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sicurezza.jpg\" class=\"attachment-large size-large wp-image-66667\" alt=\"Sicurezza\" srcset=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sicurezza.jpg 1024w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sicurezza-600x338.jpg 600w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sicurezza-300x169.jpg 300w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sicurezza-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e5731e\" data-id=\"5e5731e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58759e5 elementor-widget elementor-widget-heading\" data-id=\"58759e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sicherheit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e516b3c elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"e516b3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alle Produkte der Savio Group<br \/>bieten absolute Sicherheit.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa60136 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"aa60136\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c87711\" data-id=\"2c87711\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-678131c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"678131c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ed1bec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ed1bec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17c56bf\" data-id=\"17c56bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dc995c elementor-widget elementor-widget-heading\" data-id=\"2dc995c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nachhaltigkeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9018955 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"9018955\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ein kontinuierliches Engagement<br \/>f\u00fcr die Nutzung nachhaltiger Energie<br \/>und den Verzicht auf Plastik.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1612e12\" data-id=\"1612e12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-595d37b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"595d37b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sostenibilita.jpg\" class=\"attachment-large size-large wp-image-66673\" alt=\"Sostenibilit\u00e0\" srcset=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sostenibilita.jpg 1024w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sostenibilita-600x338.jpg 600w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sostenibilita-300x169.jpg 300w, https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/Sostenibilita-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdc1c6a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cdc1c6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-563f80f\" data-id=\"563f80f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8e66c8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d8e66c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe880e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fbe880e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05ee544 elementor-widget elementor-widget-heading\" data-id=\"05ee544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kontaktieren sie uns!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6e70a1 elementor-widget elementor-widget-text-editor\" data-id=\"f6e70a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00f6chten Sie \u00fcber neue Produkte, Kurse von SAVIO und unsere Initiativen informiert werden?<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>UNTERNEHMEN Savio Group Qualit\u00e4t ist unser Ziel&#8230; seit 130 Jahren Die Qualit\u00e4t und Innovation der Produkte der Savio Group (mehr als 5.600 im Katalog) beruht auf \u00fcber 190 weltweit angemeldeten Patenten. Savio Group ist auf der ganzen Welt vertreten, mit einem weit verzweigten Netz von Vertriebspartnern und Niederlassungen, die einen globalen Vertrieb von Produkten \u201eMade&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-117538","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unternehmen - SAVIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/savio.it\/de\/azienda\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unternehmen - SAVIO\" \/>\n<meta property=\"og:description\" content=\"UNTERNEHMEN Savio Group Qualit\u00e4t ist unser Ziel&#8230; seit 130 Jahren Die Qualit\u00e4t und Innovation der Produkte der Savio Group (mehr als 5.600 im Katalog) beruht auf \u00fcber 190 weltweit angemeldeten Patenten. Savio Group ist auf der ganzen Welt vertreten, mit einem weit verzweigten Netz von Vertriebspartnern und Niederlassungen, die einen globalen Vertrieb von Produkten \u201eMade&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/savio.it\/de\/azienda\/\" \/>\n<meta property=\"og:site_name\" content=\"SAVIO\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-15T13:33:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/\",\"url\":\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/\",\"name\":\"Unternehmen - SAVIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/savio.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-qualita-il-nostro-obiettivo.jpg\",\"datePublished\":\"2023-12-15T11:14:38+00:00\",\"dateModified\":\"2023-12-15T13:33:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/savio.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-qualita-il-nostro-obiettivo.jpg\",\"contentUrl\":\"https:\\\/\\\/savio.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-qualita-il-nostro-obiettivo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/azienda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/savio.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/savio.it\\\/de\\\/\",\"name\":\"SAVIO\",\"description\":\"Open mind for closing system\",\"publisher\":{\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/savio.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/#organization\",\"name\":\"SAVIO\",\"url\":\"https:\\\/\\\/savio.it\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/savio.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-Savio-logo.png\",\"contentUrl\":\"https:\\\/\\\/savio.it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-Savio-logo.png\",\"width\":243,\"height\":64,\"caption\":\"SAVIO\"},\"image\":{\"@id\":\"https:\\\/\\\/savio.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unternehmen - SAVIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/savio.it\/de\/azienda\/","og_locale":"de_DE","og_type":"article","og_title":"Unternehmen - SAVIO","og_description":"UNTERNEHMEN Savio Group Qualit\u00e4t ist unser Ziel&#8230; seit 130 Jahren Die Qualit\u00e4t und Innovation der Produkte der Savio Group (mehr als 5.600 im Katalog) beruht auf \u00fcber 190 weltweit angemeldeten Patenten. Savio Group ist auf der ganzen Welt vertreten, mit einem weit verzweigten Netz von Vertriebspartnern und Niederlassungen, die einen globalen Vertrieb von Produkten \u201eMade&hellip;","og_url":"https:\/\/savio.it\/de\/azienda\/","og_site_name":"SAVIO","article_modified_time":"2023-12-15T13:33:29+00:00","og_image":[{"url":"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/savio.it\/de\/azienda\/","url":"https:\/\/savio.it\/de\/azienda\/","name":"Unternehmen - SAVIO","isPartOf":{"@id":"https:\/\/savio.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/savio.it\/de\/azienda\/#primaryimage"},"image":{"@id":"https:\/\/savio.it\/de\/azienda\/#primaryimage"},"thumbnailUrl":"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo.jpg","datePublished":"2023-12-15T11:14:38+00:00","dateModified":"2023-12-15T13:33:29+00:00","breadcrumb":{"@id":"https:\/\/savio.it\/de\/azienda\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/savio.it\/de\/azienda\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/savio.it\/de\/azienda\/#primaryimage","url":"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo.jpg","contentUrl":"https:\/\/savio.it\/wp-content\/uploads\/2022\/03\/La-qualita-il-nostro-obiettivo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/savio.it\/de\/azienda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/savio.it\/de\/"},{"@type":"ListItem","position":2,"name":"Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/savio.it\/de\/#website","url":"https:\/\/savio.it\/de\/","name":"SAVIO","description":"Open mind for closing system","publisher":{"@id":"https:\/\/savio.it\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/savio.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/savio.it\/de\/#organization","name":"SAVIO","url":"https:\/\/savio.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/savio.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/savio.it\/wp-content\/uploads\/2021\/09\/cropped-Savio-logo.png","contentUrl":"https:\/\/savio.it\/wp-content\/uploads\/2021\/09\/cropped-Savio-logo.png","width":243,"height":64,"caption":"SAVIO"},"image":{"@id":"https:\/\/savio.it\/de\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"gs-tiny":false,"xl":false,"xxl":false,"xxxl":false,"xxxxl":false,"xxxxxl":false,"1536x1536":false,"2048x2048":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"admin_news","author_link":"https:\/\/savio.it\/de\/author\/admin_news\/"},"uagb_comment_info":0,"uagb_excerpt":"UNTERNEHMEN Savio Group Qualit\u00e4t ist unser Ziel&#8230; seit 130 Jahren Die Qualit\u00e4t und Innovation der Produkte der Savio Group (mehr als 5.600 im Katalog) beruht auf \u00fcber 190 weltweit angemeldeten Patenten. Savio Group ist auf der ganzen Welt vertreten, mit einem weit verzweigten Netz von Vertriebspartnern und Niederlassungen, die einen globalen Vertrieb von Produkten \u201eMade&hellip;","_links":{"self":[{"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/pages\/117538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/comments?post=117538"}],"version-history":[{"count":1,"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/pages\/117538\/revisions"}],"predecessor-version":[{"id":117539,"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/pages\/117538\/revisions\/117539"}],"wp:attachment":[{"href":"https:\/\/savio.it\/de\/wp-json\/wp\/v2\/media?parent=117538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}