{"id":34494,"date":"2021-09-30T12:41:21","date_gmt":"2021-10-05T10:39:14","guid":{"rendered":"https:\/\/savio.ne-ws.it\/prodotto\/3150-800\/"},"modified":"2026-05-12T02:02:10","modified_gmt":"2026-05-12T02:02:10","slug":"3150-800","status":"publish","type":"product","link":"https:\/\/savio.it\/es\/prodotto\/3150-800\/","title":{"rendered":"3150.800"},"content":{"rendered":"<p>Comp\u00e1s suplementario para la maniobra tradicional, en acero inox 304, zamac cindado negro y nylon negro, pletina en aluminio pre-anodizado, 2 tornillos con cabeza cil\u00edndrica \u00d8 4,2&#215;13 en acero inox 304.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comp\u00e1s suplementario para la maniobra tradicional<\/p>\n","protected":false},"featured_media":138033,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[12589],"product_tag":[13131],"profilo":[11995,11996,12040,12393,12394,12395,12396,12398,12399,12061,12062,12479,12480,12481,12411,12412,12104,12105,12134,12135,12136,12137,12111,12125,12112,12139,12388,12389,12267,12441,12442,12445,12446,12448,12449,12451,12452,12461,12462,12453,12464,12465,12456,12458,12320,12339,12346,12321,12322,12323,12340,12347,12324,12345,12325,12348,11980,11981,11982,11983,12417,12416,12423,12425,12426,12427,12428,12429,12430,12006,12007,12095,12096,12008,12009,12010,12098,12011,12035,12036,12034,12038,12152,12153,12164,12166,12154,12155,12156,12180,12181,12157,12182,12183,12482,12483,12470,12468,12469,12434,12014,12015,12016,12247,12266,12248,12249,12219,12186,12187,12196,12197,12198,12218,12220,12199,12200,12201,12227,12202,12235,12236,12064,11970,11971,11969,11968,11972,11973,11974,12169,12170,12173,12172,12174,12171,12175,12177,12178,12085,12372,12373,12476,12477,12487,12488,12088,12089,12090,12091,12489,12490,12086,12355,12361,12357,12363,12356,12362,12358,12359,12364,12229,12044,12051,12052,12045,12046,12053,12484,12246,12435,12437,12436,12438,12274,12275,12276,12304,12305,12277,12293,12299,12300,12296,12297,12301,12302,12298,12311,12312,12313,12315,12314,12316],"finiture":[],"gruppo_anta":[2956,2958],"class_list":{"0":"post-34494","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anta-ribalta-e-accessori","7":"product_tag-updated-es","8":"profilo-alfil-a54rpt","9":"profilo-alfil-a65rpt","10":"profilo-allco-tec-72","11":"profilo-atlantis-45","12":"profilo-atlantis-45-raggiato","13":"profilo-atlantis-55-tt","14":"profilo-atlantis-55-tt-raggiato","15":"profilo-atlantis-68-tt","16":"profilo-atlantis-68-tt-raggiato","17":"profilo-bga-50","18":"profilo-bga-50-arrotondato","19":"profilo-bronze-window","20":"profilo-calm-door","21":"profilo-calm-window","22":"profilo-cx-600","23":"profilo-cx-700","24":"profilo-domal-break-pa-52","25":"profilo-domal-break-pa-52-raggiato","26":"profilo-domal-bright-pa-70-s","27":"profilo-domal-bright-pa-70-s-raggiato","28":"profilo-domal-extratermic-62","29":"profilo-domal-extratermic-62-raggiato","30":"profilo-domal-stopper-pg","31":"profilo-domal-stopper-pg-63","32":"profilo-domal-stopper-pg-raggiato","33":"profilo-domal-top-tb-65","34":"profilo-ecowin-th-62","35":"profilo-ecowin-th-72","36":"profilo-ekip-th-83","37":"profilo-ekos-50-sh","38":"profilo-ekos-50-sh-raggiato","39":"profilo-ekos-50-th","40":"profilo-ekos-50-th-raggiato","41":"profilo-ekos-58-thm","42":"profilo-ekos-58-thm-raggiato","43":"profilo-ekos-66-th","44":"profilo-ekos-66-th-raggiato","45":"profilo-ekos-68-thr","46":"profilo-ekos-68-thr-raggiato","47":"profilo-ekos-75-th","48":"profilo-ekos-85-th","49":"profilo-ekos-85-th-raggiato","50":"profilo-ekos-minimall-54-th","51":"profilo-ekos-minimall-62-thj","52":"profilo-eku-40","53":"profilo-eku-40-raggiato","54":"profilo-eku-52-tt","55":"profilo-eku-53","56":"profilo-eku-53-raggiato","57":"profilo-eku-53-tt","58":"profilo-eku-53-tt-raggiato","59":"profilo-eku-62-tt","60":"profilo-eku-64-tt","61":"profilo-eku-66-tt","62":"profilo-eku-72-tt","63":"profilo-eku-78-tt","64":"profilo-esedra-ga-53","65":"profilo-esedra-ga-53-raggiato","66":"profilo-esedra-tt-63","67":"profilo-esedra-tt-75","68":"profilo-et-45-sormonto","69":"profilo-et-45-sormonto-raggiato","70":"profilo-et-58-2-tt","71":"profilo-et-67-3-tt","72":"profilo-et-67-3-tt-raggiato","73":"profilo-et-68-2-tt","74":"profilo-et-68-2-tt-raggiato","75":"profilo-et-75-3-tt","76":"profilo-et-75-3-tt-raggiato","77":"profilo-export-45","78":"profilo-export-45-raggiato","79":"profilo-export-45-t","80":"profilo-export-45-t-raggiato","81":"profilo-export-45-tt","82":"profilo-export-45-tt-raggiato","83":"profilo-export-50","84":"profilo-export-50-t","85":"profilo-export-50-tt","86":"profilo-export-51-tt","87":"profilo-export-51-tt-raggiato","88":"profilo-export-68-tt","89":"profilo-export-68-tt-raggiato","90":"profilo-gold-400","91":"profilo-gold-400-raggiato","92":"profilo-gold-450","93":"profilo-gold-450-tt","94":"profilo-gold-490-tt","95":"profilo-gold-500","96":"profilo-gold-500-raggiato","97":"profilo-gold-502-hc","98":"profilo-gold-502-hc-raggiato","99":"profilo-gold-600","100":"profilo-gold-600-hc","101":"profilo-gold-600-hc-raggiato","102":"profilo-golden-silver-door","103":"profilo-golden-silver-window","104":"profilo-hf-580","105":"profilo-hp-600","106":"profilo-hp-700","107":"profilo-iblea-color","108":"profilo-k-45t","109":"profilo-k-64t","110":"profilo-k-70t","111":"profilo-maastricht-53","112":"profilo-maastricht-light","113":"profilo-maastricht-th-60","114":"profilo-maastricht-th-68","115":"profilo-metraltech","116":"profilo-mx-50","117":"profilo-mx-70","118":"profilo-nc-45-int","119":"profilo-nc-45-int-raggiato","120":"profilo-nc-45-sth","121":"profilo-nc-50-i","122":"profilo-nc-50-sth","123":"profilo-nc-55-int","124":"profilo-nc-65-sth","125":"profilo-nc-68-sth","126":"profilo-nc-68-sth-s","127":"profilo-nc-72-sth","128":"profilo-nc-75-sth","129":"profilo-nc-75-sthi","130":"profilo-new-bt-60-tt","131":"profilo-planet-45","132":"profilo-planet-45-raggiato","133":"profilo-planet-50-raggiato","134":"profilo-planet-50-tt","135":"profilo-planet-62-tt","136":"profilo-planet-62-tt-raggiato","137":"profilo-planet-72-ht","138":"profilo-plathina-60-antares","139":"profilo-plathina-60-classica","140":"profilo-plathina-60-flat-antares","141":"profilo-plathina-60-flat-classica","142":"profilo-plathina-60-flat-rustica","143":"profilo-plathina-60-rustica","144":"profilo-plathina-69-classica","145":"profilo-plathina-69-flat-classica","146":"profilo-plathina-75-classica","147":"profilo-prestige-73-tt","148":"profilo-road-520-tt-ce","149":"profilo-road-600-tt-ce","150":"profilo-serie-6000","151":"profilo-serie-6500-rpt","152":"profilo-serie-751","153":"profilo-serie-769","154":"profilo-serie-8000","155":"profilo-serie-8000-raggiato","156":"profilo-serie-8000-tt","157":"profilo-serie-8000-tt-raggiato","158":"profilo-serie-801","159":"profilo-serie-901","160":"profilo-slim-70-tt","161":"profilo-start-410","162":"profilo-start-410-raggiato","163":"profilo-start-470-tt","164":"profilo-start-470-tt-raggiato","165":"profilo-start-510","166":"profilo-start-510-raggiato","167":"profilo-start-560-tt","168":"profilo-start-640-tt","169":"profilo-start-760-tt","170":"profilo-superblindo","171":"profilo-synthesis-45","172":"profilo-synthesis-52","173":"profilo-synthesis-52-tt","174":"profilo-synthesis-57","175":"profilo-synthesis-60-tt","176":"profilo-synthesis-68-tt","177":"profilo-uah-100-window-bullet-proof","178":"profilo-venice-th16","179":"profilo-vuerre-53-tt","180":"profilo-vuerre-53-tt-raggiato","181":"profilo-vuerre-70-tt","182":"profilo-vuerre-70-tt-raggiato","183":"profilo-windstop-45","184":"profilo-windstop-45-raggiato","185":"profilo-windstop-45-tt","186":"profilo-windstop-45-tt-classic","187":"profilo-windstop-45-tt-classic-raggiato","188":"profilo-windstop-45-tt-raggiato","189":"profilo-windstop-55-tt","190":"profilo-windstop-55-tt-classic","191":"profilo-windstop-55-tt-classic-raggiato","192":"profilo-windstop-55-tt-raggiato","193":"profilo-windstop-65-tt","194":"profilo-windstop-65-tt-classic","195":"profilo-windstop-65-tt-classic-raggiato","196":"profilo-windstop-65-tt-raggiato","197":"profilo-windstop-73-tt","198":"profilo-windstop-73-tt-raggiato","199":"profilo-ws-65-thi","200":"profilo-ws-65-thi-raggiato","201":"profilo-ws-75-thi","202":"profilo-ws-75-thi-raggiato","203":"gruppo_anta-2956","204":"gruppo_anta-2958","205":"description-off","207":"first","208":"onbackorder","209":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3150.800<\/title>\n<meta name=\"description\" content=\"Comp\u00e1s suplementario para la maniobra tradicional\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/savio.it\/es\/prodotto\/3150-800\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3150.800\" \/>\n<meta property=\"og:description\" content=\"Comp\u00e1s suplementario para la maniobra tradicional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/savio.it\/es\/prodotto\/3150-800\/\" \/>\n<meta property=\"og:site_name\" content=\"SAVIO\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T02:02:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/savio.it\/es\/prodotto\/3150-800\/\",\"url\":\"https:\/\/savio.it\/es\/prodotto\/3150-800\/\",\"name\":\"3150.800\",\"isPartOf\":{\"@id\":\"https:\/\/savio.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/savio.it\/es\/prodotto\/3150-800\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/savio.it\/es\/prodotto\/3150-800\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg\",\"datePublished\":\"2021-10-05T10:39:14+00:00\",\"dateModified\":\"2026-05-12T02:02:10+00:00\",\"description\":\"Comp\u00e1s suplementario para la maniobra tradicional\",\"breadcrumb\":{\"@id\":\"https:\/\/savio.it\/es\/prodotto\/3150-800\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/savio.it\/es\/prodotto\/3150-800\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/savio.it\/es\/prodotto\/3150-800\/#primaryimage\",\"url\":\"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg\",\"contentUrl\":\"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/savio.it\/es\/prodotto\/3150-800\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/savio.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/savio.it\/es\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3150.800\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/savio.it\/es\/#website\",\"url\":\"https:\/\/savio.it\/es\/\",\"name\":\"SAVIO\",\"description\":\"Open mind for closing system\",\"publisher\":{\"@id\":\"https:\/\/savio.it\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/savio.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/savio.it\/es\/#organization\",\"name\":\"SAVIO\",\"url\":\"https:\/\/savio.it\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/savio.it\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/savio.it\/wp-content\/uploads\/2021\/09\/cropped-Savio-logo.png\",\"contentUrl\":\"https:\/\/savio.it\/wp-content\/uploads\/2021\/09\/cropped-Savio-logo.png\",\"width\":243,\"height\":64,\"caption\":\"SAVIO\"},\"image\":{\"@id\":\"https:\/\/savio.it\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3150.800","description":"Comp\u00e1s suplementario para la maniobra tradicional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/savio.it\/es\/prodotto\/3150-800\/","og_locale":"es_ES","og_type":"article","og_title":"3150.800","og_description":"Comp\u00e1s suplementario para la maniobra tradicional","og_url":"https:\/\/savio.it\/es\/prodotto\/3150-800\/","og_site_name":"SAVIO","article_modified_time":"2026-05-12T02:02:10+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/savio.it\/es\/prodotto\/3150-800\/","url":"https:\/\/savio.it\/es\/prodotto\/3150-800\/","name":"3150.800","isPartOf":{"@id":"https:\/\/savio.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/savio.it\/es\/prodotto\/3150-800\/#primaryimage"},"image":{"@id":"https:\/\/savio.it\/es\/prodotto\/3150-800\/#primaryimage"},"thumbnailUrl":"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg","datePublished":"2021-10-05T10:39:14+00:00","dateModified":"2026-05-12T02:02:10+00:00","description":"Comp\u00e1s suplementario para la maniobra tradicional","breadcrumb":{"@id":"https:\/\/savio.it\/es\/prodotto\/3150-800\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/savio.it\/es\/prodotto\/3150-800\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/savio.it\/es\/prodotto\/3150-800\/#primaryimage","url":"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg","contentUrl":"https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/savio.it\/es\/prodotto\/3150-800\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/savio.it\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/savio.it\/es\/prodotti\/"},{"@type":"ListItem","position":3,"name":"3150.800"}]},{"@type":"WebSite","@id":"https:\/\/savio.it\/es\/#website","url":"https:\/\/savio.it\/es\/","name":"SAVIO","description":"Open mind for closing system","publisher":{"@id":"https:\/\/savio.it\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/savio.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/savio.it\/es\/#organization","name":"SAVIO","url":"https:\/\/savio.it\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/savio.it\/es\/#\/schema\/logo\/image\/","url":"https:\/\/savio.it\/wp-content\/uploads\/2021\/09\/cropped-Savio-logo.png","contentUrl":"https:\/\/savio.it\/wp-content\/uploads\/2021\/09\/cropped-Savio-logo.png","width":243,"height":64,"caption":"SAVIO"},"image":{"@id":"https:\/\/savio.it\/es\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"thumbnail":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800-150x150.jpg",150,150,true],"medium":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800-300x300.jpg",300,300,true],"medium_large":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800-768x768.jpg",768,768,true],"large":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"gs-tiny":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",50,50,false],"xl":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"xxl":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"xxxl":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"xxxxl":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"xxxxxl":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"1536x1536":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"2048x2048":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800.jpg",1000,1000,false],"woocommerce_thumbnail":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800-600x600.jpg",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/savio.it\/wp-content\/uploads\/2022\/06\/3150_800-200x200.jpg",200,200,true]},"uagb_author_info":{"display_name":"admin_news","author_link":"https:\/\/savio.it\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Comp\u00e1s suplementario para la maniobra tradicional","_links":{"self":[{"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/product\/34494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/comments?post=34494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/media\/138033"}],"wp:attachment":[{"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/media?parent=34494"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/product_brand?post=34494"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/product_cat?post=34494"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/product_tag?post=34494"},{"taxonomy":"profilo","embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/profilo?post=34494"},{"taxonomy":"finiture","embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/finiture?post=34494"},{"taxonomy":"gruppo_anta","embeddable":true,"href":"https:\/\/savio.it\/es\/wp-json\/wp\/v2\/gruppo_anta?post=34494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}